{"id":2764,"date":"2010-07-15T07:31:51","date_gmt":"2010-07-15T06:31:51","guid":{"rendered":"http:\/\/www.1erdegre.ch\/blog\/?p=2764"},"modified":"2011-12-14T23:33:14","modified_gmt":"2011-12-14T22:33:14","slug":"pour-toi-qui-na-pas-diphone","status":"publish","type":"post","link":"https:\/\/www.1erdegre.ch\/blog\/2010\/07\/15\/pour-toi-qui-na-pas-diphone\/","title":{"rendered":"Pour toi, qui n&rsquo;a pas d&rsquo;iPhone!"},"content":{"rendered":"<p><a href=\"http:\/\/www.1erdegre.ch\/blog\/wp-content\/uploads\/cauchemar.png\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.1erdegre.ch\/blog\/wp-content\/uploads\/cauchemar.png\" alt=\"\" title=\"cauchemar\" width=\"709\" height=\"223\"\" class=\"alignnone size-full wp-image-2765\" srcset=\"https:\/\/www.1erdegre.ch\/blog\/wp-content\/uploads\/cauchemar.png 709w, https:\/\/www.1erdegre.ch\/blog\/wp-content\/uploads\/cauchemar-300x94.png 300w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/><\/a><\/p>\n<p><strong>Strip paru sur l&rsquo;application de <a href=\"http:\/\/www.hebdo.ch\">L&rsquo;Hebdo<\/a>.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-2764","post","type-post","status-publish","format-standard","hentry","category-les-strips"],"_links":{"self":[{"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/posts\/2764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/comments?post=2764"}],"version-history":[{"count":6,"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/posts\/2764\/revisions"}],"predecessor-version":[{"id":4751,"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/posts\/2764\/revisions\/4751"}],"wp:attachment":[{"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/media?parent=2764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/categories?post=2764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/tags?post=2764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}