{"id":1172,"date":"2007-11-19T01:30:10","date_gmt":"2007-11-18T23:30:10","guid":{"rendered":"http:\/\/www.1erdegre.ch\/blog\/archives\/1172"},"modified":"2025-01-03T11:59:04","modified_gmt":"2025-01-03T10:59:04","slug":"au-royaume-des-tenebres","status":"publish","type":"post","link":"https:\/\/www.1erdegre.ch\/blog\/2007\/11\/19\/au-royaume-des-tenebres\/","title":{"rendered":"Au Royaume des T\u00e9n\u00e8bres"},"content":{"rendered":"<p><img src='http:\/\/www.1erdegre.ch\/blog\/wp-content\/uploads\/ampoule.jpg' alt='ampoule.jpg' \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1172","post","type-post","status-publish","format-standard","hentry","category-humour"],"_links":{"self":[{"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/posts\/1172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/comments?post=1172"}],"version-history":[{"count":1,"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/posts\/1172\/revisions"}],"predecessor-version":[{"id":3752,"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/posts\/1172\/revisions\/3752"}],"wp:attachment":[{"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/media?parent=1172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/categories?post=1172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.1erdegre.ch\/blog\/wp-json\/wp\/v2\/tags?post=1172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}